{"id":11498,"date":"2026-07-10T02:32:02","date_gmt":"2026-07-10T00:32:02","guid":{"rendered":"https:\/\/selapercussion.com\/product\/sech9nt\/"},"modified":"2026-07-10T02:32:02","modified_gmt":"2026-07-10T00:32:02","slug":"sech9nt","status":"publish","type":"product","link":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/","title":{"rendered":"SECH9NT"},"featured_media":23070,"template":"","product-cat-sela":[287],"class_list":["post-11498","product","type-product","status-publish","has-post-thumbnail","hentry","product-cat-sela-wind-chimes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SECH9NT - Sela Percussion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selapercussion.com\/de\/products\/sech9nt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SECH9NT - Sela Percussion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selapercussion.com\/de\/products\/sech9nt\/\" \/>\n<meta property=\"og:site_name\" content=\"Sela Percussion\" \/>\n<meta property=\"og:image\" content=\"https:\/\/selapercussion.com\/wp-content\/uploads\/sech9nt_00-1920x1920.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/\",\"url\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/\",\"name\":\"SECH9NT - Sela Percussion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/selapercussion.com\\\/wp-content\\\/uploads\\\/sech9nt_00.png\",\"datePublished\":\"2026-07-10T00:32:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/selapercussion.com\\\/wp-content\\\/uploads\\\/sech9nt_00.png\",\"contentUrl\":\"https:\\\/\\\/selapercussion.com\\\/wp-content\\\/uploads\\\/sech9nt_00.png\",\"width\":2063,\"height\":2064},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/sech9nt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SELA\",\"item\":\"https:\\\/\\\/selapercussion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chimes &amp; Bells\",\"item\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/chimes-bells\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wind Chimes\",\"item\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/products\\\/chimes-bells\\\/wind-chime\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"SECH9NT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/\",\"name\":\"Sela Percussion\",\"description\":\"the soul of sound\",\"publisher\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#organization\",\"name\":\"Sela Percussion\",\"url\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/selapercussion.com\\\/wp-content\\\/uploads\\\/Logo-SELA.svg\",\"contentUrl\":\"https:\\\/\\\/selapercussion.com\\\/wp-content\\\/uploads\\\/Logo-SELA.svg\",\"caption\":\"Sela Percussion\"},\"image\":{\"@id\":\"https:\\\/\\\/selapercussion.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SECH9NT - Sela Percussion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/","og_locale":"de_DE","og_type":"article","og_title":"SECH9NT - Sela Percussion","og_url":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/","og_site_name":"Sela Percussion","og_image":[{"width":1920,"height":1920,"url":"https:\/\/selapercussion.com\/wp-content\/uploads\/sech9nt_00-1920x1920.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/","url":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/","name":"SECH9NT - Sela Percussion","isPartOf":{"@id":"https:\/\/selapercussion.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/#primaryimage"},"image":{"@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/#primaryimage"},"thumbnailUrl":"https:\/\/selapercussion.com\/wp-content\/uploads\/sech9nt_00.png","datePublished":"2026-07-10T00:32:02+00:00","breadcrumb":{"@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/selapercussion.com\/de\/products\/sech9nt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/#primaryimage","url":"https:\/\/selapercussion.com\/wp-content\/uploads\/sech9nt_00.png","contentUrl":"https:\/\/selapercussion.com\/wp-content\/uploads\/sech9nt_00.png","width":2063,"height":2064},{"@type":"BreadcrumbList","@id":"https:\/\/selapercussion.com\/de\/products\/sech9nt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SELA","item":"https:\/\/selapercussion.com\/"},{"@type":"ListItem","position":2,"name":"Chimes &amp; Bells","item":"https:\/\/selapercussion.com\/de\/products\/chimes-bells\/"},{"@type":"ListItem","position":3,"name":"Wind Chimes","item":"https:\/\/selapercussion.com\/de\/products\/chimes-bells\/wind-chime\/"},{"@type":"ListItem","position":4,"name":"SECH9NT"}]},{"@type":"WebSite","@id":"https:\/\/selapercussion.com\/de\/#website","url":"https:\/\/selapercussion.com\/de\/","name":"Sela Percussion","description":"the soul of sound","publisher":{"@id":"https:\/\/selapercussion.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selapercussion.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/selapercussion.com\/de\/#organization","name":"Sela Percussion","url":"https:\/\/selapercussion.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/selapercussion.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/selapercussion.com\/wp-content\/uploads\/Logo-SELA.svg","contentUrl":"https:\/\/selapercussion.com\/wp-content\/uploads\/Logo-SELA.svg","caption":"Sela Percussion"},"image":{"@id":"https:\/\/selapercussion.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/product\/11498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/media\/23070"}],"wp:attachment":[{"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/media?parent=11498"}],"wp:term":[{"taxonomy":"product-cat-sela","embeddable":true,"href":"https:\/\/selapercussion.com\/de\/wp-json\/wp\/v2\/product-cat-sela?post=11498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}